{"id":1779,"date":"2020-04-28T10:05:42","date_gmt":"2020-04-28T08:05:42","guid":{"rendered":"https:\/\/www.fotografo-profesional.net\/diario\/?p=1779"},"modified":"2020-06-29T19:01:28","modified_gmt":"2020-06-29T17:01:28","slug":"la-farmacia-juanse-de-madrid","status":"publish","type":"post","link":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/","title":{"rendered":"La farmacia Juanse de Madrid"},"content":{"rendered":"<h4><img decoding=\"async\" class=\"alignnone size-full wp-image-1804\" src=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2020\/04\/Fot\u00f3grafo-profesional-en-Madrid-LMC-0087.jpg\" alt=\"Farmacia Juanse de Madrid\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2020\/04\/Fot\u00f3grafo-profesional-en-Madrid-LMC-0087.jpg 600w, https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2020\/04\/Fot\u00f3grafo-profesional-en-Madrid-LMC-0087-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/h4>\n<h4>Madrid preol\u00edmpica (0001). Distrito de Centro.<\/h4>\n<p>La farmacia Juanse fue <strong>inaugurada en 1892 en el barrio de Universidad<\/strong>, m\u00e1s conocido popularmente como de Malasa\u00f1a, debido a que la calle dedicada a la hero\u00edna madrile\u00f1a durante la guerra de la independencia contra los franceses se encuentra en este barrio.<\/p>\n<p>Tambi\u00e9n, porque la plaza del Dos de Mayo -fecha clave en esa guerra- es el centro neur\u00e1lgico del barrio y ha sido escenario de infinidad de actos populares desde los a\u00f1os ochenta del siglo pasado. Lo de Universidad quedaba demasiado serio para un barrio en el que estaban los baretos m\u00e1s modernos y por el que se sol\u00edan mover los personajes m\u00e1s significativos de la noche y de lo que se conoci\u00f3 como La Movida madrile\u00f1a.<\/p>\n<p>Al viandante que no est\u00e1 acostumbrado a transitar por all\u00ed lo primero que le llama la atenci\u00f3n de la farmacia Juanse es su fachada de azulejos, por lo que muchos fot\u00f3grafos se detienen a <a href=\"https:\/\/www.fotografo-profesional.net\/diario\/2019\/01\/10\/fotografos-en-madrid-preolimpica-por-retiro\/\"><span style=\"color: #0000ff;\"><em>inmortalizarla en una estampa<\/em><\/span><\/a>. Los paneles de azulejos fueron fabricados e instalados hacia 1920. Son la peculiar forma que en aquella \u00e9poca <a href=\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/03\/03\/fotografia-de-producto-para-catalogo\/\"><span style=\"color: #0000ff;\"><em>se hac\u00eda publicidad<\/em><\/span><\/a> de los productos que se pod\u00edan encontrar en algunos establecimientos.<\/p>\n<p>Desgraciadamente, a pesar de la concienzuda restauraci\u00f3n y limpieza a la que se los someti\u00f3 al local y a la fachada, la est\u00fapida obsesi\u00f3n de algunos por pintarrajear y destruir el patrimonio cultural com\u00fan parece que cada vez abunda m\u00e1s en algunas zonas y a algunas horas del d\u00eda.<\/p>\n<h4>Fin como farmacia<\/h4>\n<p>Cerr\u00f3 en 2013 y tuvo muy dif\u00edcil volver a abrir como farmacia debido a la normativa vigente en ese momento para ese tipo de negocios. Tan dif\u00edcil, que volver\u00eda a abrir en 2014, esta vez como cafeter\u00eda, tras una reforma para adaptarla a su nuevo uso aunque respetando los elementos m\u00e1s llamativos y significativos de su anterior actividad. Tambi\u00e9n los azulejos de la fachada en los que aparece el nombre de la farmacia Juanse, por el que se la sigue conociendo popularmente.<\/p>\n<p>Desde entonces ha habido varios intentos de sacar adelante el local dedic\u00e1ndolo a su uso como cafeter\u00eda con gastronom\u00eda.<\/p>\n<p>La fotograf\u00eda la tom\u00e9 en 2003, cuando todav\u00eda funcionaba como farmacia, como se puede apreciar por su ne\u00f3n encendido. \u00c9ste, l\u00f3gicamente, se desmontar\u00eda para iniciar la nueva actividad. La naturalidad de las personas que aparecen en la imagen se debe a que <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.fotografo-profesional.net\"><em>no me tomaron por fot\u00f3grafo<\/em> <\/a><em>profesional<\/em><\/span> sino por turista o a que en ese barrio est\u00e1n muy acostumbrados a ver gente haciendo fotograf\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid preol\u00edmpica (0001). Distrito de Centro. La farmacia Juanse fue inaugurada en 1892 en el barrio de Universidad, m\u00e1s conocido popularmente como de Malasa\u00f1a, debido a que la calle dedicada a la hero\u00edna madrile\u00f1a durante la guerra de la independencia contra los franceses se encuentra en este barrio. Tambi\u00e9n, porque la plaza del Dos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1804,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,48,45,215],"tags":[428,110,117,59,119,120,307,170,429,145],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La farmacia Juanse de Madrid - Luis Miguel del Campo<\/title>\n<meta name=\"description\" content=\"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La farmacia Juanse de Madrid - Luis Miguel del Campo\" \/>\n<meta property=\"og:description\" content=\"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Luis Miguel del Campo\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T08:05:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T17:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2020\/04\/Fot\u00f3grafo-profesional-en-Madrid-LMC-0087.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Miguel del Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Miguel del Campo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/\",\"name\":\"La farmacia Juanse de Madrid - Luis Miguel del Campo\",\"isPartOf\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\"},\"datePublished\":\"2020-04-28T08:05:42+00:00\",\"dateModified\":\"2020-06-29T17:01:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\"},\"description\":\"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.fotografo-profesional.net\/diario\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La farmacia Juanse de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/\",\"name\":\"Luis Miguel del Campo\",\"description\":\"Blog de un fot\u00f3grafo profesional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\",\"name\":\"Luis Miguel del Campo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"caption\":\"Luis Miguel del Campo\"},\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La farmacia Juanse de Madrid - Luis Miguel del Campo","description":"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"La farmacia Juanse de Madrid - Luis Miguel del Campo","og_description":"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.","og_url":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/","og_site_name":"Luis Miguel del Campo","article_published_time":"2020-04-28T08:05:42+00:00","article_modified_time":"2020-06-29T17:01:28+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2020\/04\/Fot\u00f3grafo-profesional-en-Madrid-LMC-0087.jpg","type":"image\/jpeg"}],"author":"Luis Miguel del Campo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Miguel del Campo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/","url":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/","name":"La farmacia Juanse de Madrid - Luis Miguel del Campo","isPartOf":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website"},"datePublished":"2020-04-28T08:05:42+00:00","dateModified":"2020-06-29T17:01:28+00:00","author":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533"},"description":"La farmacia Juanse es un negocio centenario cuya fachada de azulejos est\u00e1 protegida municipalmente dado su valor cultural y art\u00edstico.","breadcrumb":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2020\/04\/28\/la-farmacia-juanse-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.fotografo-profesional.net\/diario\/"},{"@type":"ListItem","position":2,"name":"La farmacia Juanse de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website","url":"https:\/\/www.fotografo-profesional.net\/diario\/","name":"Luis Miguel del Campo","description":"Blog de un fot\u00f3grafo profesional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533","name":"Luis Miguel del Campo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","caption":"Luis Miguel del Campo"},"url":"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/1779"}],"collection":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":6,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/1779\/revisions"}],"predecessor-version":[{"id":2074,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/1779\/revisions\/2074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/media\/1804"}],"wp:attachment":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/media?parent=1779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/categories?post=1779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/tags?post=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}