{"id":219,"date":"2018-09-14T18:55:19","date_gmt":"2018-09-14T18:55:19","guid":{"rendered":"https:\/\/www.fotografo-profesional.net\/diario-de-un-fotografo-profesional-en-madrid\/?p=219"},"modified":"2020-04-23T19:15:34","modified_gmt":"2020-04-23T17:15:34","slug":"lo-mas-importante-en-fotografia-de-eventos","status":"publish","type":"post","link":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/","title":{"rendered":"Lo m\u00e1s importante en fotograf\u00eda de eventos"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone wp-image-224 size-full\" title=\"Fot\u00f3grafo de eventos\" src=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2018\/09\/Fot\u00f3grafo-de-eventos-en-Madrid.jpg\" alt=\"Fotograf\u00eda de eventos en Madrid\" width=\"509\" height=\"339\" srcset=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2018\/09\/Fot\u00f3grafo-de-eventos-en-Madrid.jpg 509w, https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2018\/09\/Fot\u00f3grafo-de-eventos-en-Madrid-300x200.jpg 300w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/p>\n<p>Puedes leer muchos consejos sobre lo que que cada fot\u00f3grafo profesional de eventos te recomienda que hagas: llevar tal equipo fotogr\u00e1fico, ese objetivo maravilloso que te salvar\u00e1 de situaciones dif\u00edciles, esos consejos para tener cubierta la mayor profundidad de campo posible, d\u00f3nde te tienes que situar para captar perfectamente a <span style=\"color: #0000ff;\"><em><a style=\"color: #0000ff;\" href=\"https:\/\/www.fotografo-profesional.net\/diario\/2019\/05\/26\/reportaje-de-congreso-en-madrid\/\">todos los ponentes de un congreso<\/a><\/em><\/span> empresarial, la fotograf\u00eda espectacular de eventos que puedes hacer si&#8230;<\/p>\n<p>Todo lo anterior est\u00e1 muy bien, y seguro que <strong>cada fot\u00f3grafo te dar\u00e1 una serie de consejos y orientaciones<\/strong> fruto de la experiencia que ha ido acumulando a lo largo de todos los reportajes fotogr\u00e1ficos que ha hecho en su carrera profesional y que te servir\u00e1n para mejorar en la calidad y eficiencia de tu trabajo de fotograf\u00eda de eventos entregado al cliente.<\/p>\n<p>Adem\u00e1s, cada <a href=\"https:\/\/www.fotografo-profesional.net\/portfolio\/fotografia-de-eventos\/\"><span style=\"color: #0000ff;\"><em>categor\u00eda de reportaje<\/em><\/span> <\/a>fotogr\u00e1fico tiene sus particulares trucos seg\u00fan sea una <a href=\"https:\/\/www.fotografo-profesional.net\/diario\/2019\/12\/28\/fotografo-de-premios-de-empresa\/\"><span style=\"color: #0000ff;\"><em>convenci\u00f3n empresarial<\/em><\/span><\/a>, un seminario profesional, un congreso m\u00e9dico, conferencias de actualizaci\u00f3n de conocimientos, una feria de turismo&#8230;\u00a0<\/p>\n<p>Lo que siempre se suele aconsejar es lo que tienes que hacer durante un <strong>reportaje fotogr\u00e1fico de un evento<\/strong>, pero lo que la mayor\u00eda de las veces no se indica es lo que, bajo ning\u00fan concepto, debes hacer mientras lo cubres. Muchas veces se da por hecho que<a href=\"https:\/\/www.fotografo-profesional.net\/trayectoria\/\"><span style=\"color: #0000ff;\"><em> el profesional lo sabe<\/em><\/span><\/a> o tiene el sentido com\u00fan suficiente para no hacer tal o cual cosa.<\/p>\n<p>Desgraciadamente muchas veces el sentido com\u00fan no es tan com\u00fan. Y no todo el mundo tiene en cuenta las normas m\u00e1s elementales de educaci\u00f3n y trato cuando est\u00e1 realizando un reportaje. Y eso tambi\u00e9n ocurre en la fotograf\u00eda de eventos.<\/p>\n<h4>Normas de comportamiento<\/h4>\n<p><strong>Hacer buena fotograf\u00eda de eventos<\/strong> empieza por ser educado en el trato con todo el mundo, guardar respeto hacia todas las personas que est\u00e1n en el evento, no creerse m\u00e1s que nadie por tener una c\u00e1mara fotogr\u00e1fica entre las manos y molestar lo menos posible a los asistentes mientras haces las fotograf\u00edas \u2013por muy importante que te hayan dicho que sea ese momento. Luego, adem\u00e1s, has de captar los momentos m\u00e1s significativos con gusto, elegancia y estilo personal para entregar una fotograf\u00eda de eventos de calidad.<\/p>\n<p>Y tambi\u00e9n es fundamental <strong style=\"font-size: inherit;\">pedir permiso cuando tengas la m\u00e1s m\u00ednima duda<\/strong><span style=\"font-size: inherit;\"> sobre si debes<\/span><span style=\"font-size: inherit;\">\u00a0hacer una fotograf\u00eda o no.<\/span><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puedes leer muchos consejos sobre lo que que cada fot\u00f3grafo profesional de eventos te recomienda que hagas: llevar tal equipo fotogr\u00e1fico, ese objetivo maravilloso que te salvar\u00e1 de situaciones dif\u00edciles, esos consejos para tener cubierta la mayor profundidad de campo posible, d\u00f3nde te tienes que situar para captar perfectamente a todos los ponentes de un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,114,113,116],"tags":[124,118,32,117,59,119,120,307,123,122,121],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo<\/title>\n<meta name=\"description\" content=\"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo\" \/>\n<meta property=\"og:description\" content=\"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/\" \/>\n<meta property=\"og:site_name\" content=\"Luis Miguel del Campo\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-14T18:55:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-23T17:15:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2018\/09\/Fot\u00f3grafo-de-eventos-en-Madrid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"509\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Miguel del Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Miguel del Campo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/\",\"name\":\"Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo\",\"isPartOf\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\"},\"datePublished\":\"2018-09-14T18:55:19+00:00\",\"dateModified\":\"2020-04-23T17:15:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\"},\"description\":\"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.fotografo-profesional.net\/diario\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo m\u00e1s importante en fotograf\u00eda de eventos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/\",\"name\":\"Luis Miguel del Campo\",\"description\":\"Blog de un fot\u00f3grafo profesional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\",\"name\":\"Luis Miguel del Campo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"caption\":\"Luis Miguel del Campo\"},\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo","description":"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/","og_locale":"es_ES","og_type":"article","og_title":"Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo","og_description":"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.","og_url":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/","og_site_name":"Luis Miguel del Campo","article_published_time":"2018-09-14T18:55:19+00:00","article_modified_time":"2020-04-23T17:15:34+00:00","og_image":[{"width":509,"height":339,"url":"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2018\/09\/Fot\u00f3grafo-de-eventos-en-Madrid.jpg","type":"image\/jpeg"}],"author":"Luis Miguel del Campo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Miguel del Campo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/","url":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/","name":"Lo m\u00e1s importante en fotograf\u00eda de eventos - Luis Miguel del Campo","isPartOf":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website"},"datePublished":"2018-09-14T18:55:19+00:00","dateModified":"2020-04-23T17:15:34+00:00","author":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533"},"description":"Orientaciones sobre c\u00f3mo hacer fotograf\u00eda de eventos, ya sea en un congreso, conferencia, rueda de prensa o convenci\u00f3n empresarial.","breadcrumb":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2018\/09\/14\/lo-mas-importante-en-fotografia-de-eventos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.fotografo-profesional.net\/diario\/"},{"@type":"ListItem","position":2,"name":"Lo m\u00e1s importante en fotograf\u00eda de eventos"}]},{"@type":"WebSite","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website","url":"https:\/\/www.fotografo-profesional.net\/diario\/","name":"Luis Miguel del Campo","description":"Blog de un fot\u00f3grafo profesional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533","name":"Luis Miguel del Campo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","caption":"Luis Miguel del Campo"},"url":"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/219"}],"collection":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/comments?post=219"}],"version-history":[{"count":10,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/219\/revisions"}],"predecessor-version":[{"id":1774,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/219\/revisions\/1774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/media\/224"}],"wp:attachment":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/media?parent=219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/categories?post=219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/tags?post=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}