{"id":3088,"date":"2021-12-07T22:48:15","date_gmt":"2021-12-07T21:48:15","guid":{"rendered":"https:\/\/www.fotografo-profesional.net\/diario\/?p=3088"},"modified":"2021-12-08T09:07:50","modified_gmt":"2021-12-08T08:07:50","slug":"breve-historia-del-viaducto-de-madrid","status":"publish","type":"post","link":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/","title":{"rendered":"Breve historia del viaducto de Madrid"},"content":{"rendered":"\r\n<h3><img decoding=\"async\" class=\"size-full wp-image-3096 aligncenter\" src=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2021\/12\/Fotografo-profesional-en-madrid-LMC-0246.jpg\" alt=\"Viaducto de Madrid\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2021\/12\/Fotografo-profesional-en-madrid-LMC-0246.jpg 600w, https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2021\/12\/Fotografo-profesional-en-madrid-LMC-0246-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/h3>\r\n<h3>Estampas de Madrid (0101)<\/h3>\r\n<p>El famoso viaducto de Madrid se eleva desde la calle Segovia hasta llegar a la altura de la calle de Bail\u00e9n con el fin de sostener su prolongaci\u00f3n, que une el Palacio Real con la bas\u00edlica de San Francisco el Grande a trav\u00e9s de Las Vistillas; este \u00faltimo es el nombre popular con el que se conoce al parque y a la plaza de Gabriel Mir\u00f3, escritor de principios del siglo XX.<\/p>\r\n<p>En la<strong> plaza de Las Vistillas<\/strong> se han celebrado infinidad de verbenas populares en honor de San Isidro y de la Virgen de la Paloma desde tiempos inmemoriales. Aunque la primera, desde ya hace casi un lustro, se est\u00e1 celebrando en el parque que lleva el nombre del santo, situado en el distrito de Carabanchel.<\/p>\r\n<p>El citado viaducto de Madrid tambi\u00e9n viene siendo conocido, casi desde su construcci\u00f3n, como el puente de los suicidas. Bien es verdad que desde hace unos cuantos a\u00f1os no hace honor a su sobrenombre pues el ayuntamiento instal\u00f3 unos gruesos vidrios de gran tama\u00f1o que impiden a los desesperados llevar a cabo su prop\u00f3sito. Los reflejos que producen sus cristales a menudo tambi\u00e9n impiden el buen hacer de los fot\u00f3grafos que se acercan hasta all\u00ed para plasmar las maravillosas vistas, a no ser que sean profesionales. Porque <a href=\"https:\/\/www.fotografo-profesional.net\/servicios\/\"><span style=\"color: #0000ff;\">un buen fot\u00f3grafo profesional<\/span><\/a> siempre sabe c\u00f3mo superar esa adversidad de una u otra manera.<\/p>\r\n<p>Cabe destacar que el primer viaducto de Madrid se construy\u00f3 de hierro en 1874; obra dirigida por el arquitecto municipal Eugenio Barr\u00f3n Avignon. Con posterioridad se llevar\u00edan a cabo varias reformas hasta llegar a la edificaci\u00f3n de hormig\u00f3n que puede contemplarse en la imagen que este <strong>fot\u00f3grafo profesional<\/strong> tom\u00f3 en 2016 y encabeza este art\u00edculo.<\/p>\r\n<p>El viaducto de Madrid es una de las edificaciones m\u00e1s emblem\u00e1ticas de nuestro Madrid contempor\u00e1neo.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Estampas de Madrid (0101) El famoso viaducto de Madrid se eleva desde la calle Segovia hasta llegar a la altura de la calle de Bail\u00e9n con el fin de sostener su prolongaci\u00f3n, que une el Palacio Real con la bas\u00edlica de San Francisco el Grande a trav\u00e9s de Las Vistillas; este \u00faltimo es el nombre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[209,48,45,406,172,207],"tags":[109,110,290,99,348,284,626,338,452,812],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Breve historia del viaducto de Madrid - Luis Miguel del Campo<\/title>\n<meta name=\"description\" content=\"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breve historia del viaducto de Madrid - Luis Miguel del Campo\" \/>\n<meta property=\"og:description\" content=\"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Luis Miguel del Campo\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T21:48:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-08T08:07:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2021\/12\/Fotografo-profesional-en-madrid-LMC-0246.jpg\" \/>\n<meta name=\"author\" content=\"Luis Miguel del Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Miguel del Campo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/\",\"name\":\"Breve historia del viaducto de Madrid - Luis Miguel del Campo\",\"isPartOf\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\"},\"datePublished\":\"2021-12-07T21:48:15+00:00\",\"dateModified\":\"2021-12-08T08:07:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\"},\"description\":\"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.fotografo-profesional.net\/diario\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Breve historia del viaducto de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#website\",\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/\",\"name\":\"Luis Miguel del Campo\",\"description\":\"Blog de un fot\u00f3grafo profesional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533\",\"name\":\"Luis Miguel del Campo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g\",\"caption\":\"Luis Miguel del Campo\"},\"url\":\"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breve historia del viaducto de Madrid - Luis Miguel del Campo","description":"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Breve historia del viaducto de Madrid - Luis Miguel del Campo","og_description":"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.","og_url":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/","og_site_name":"Luis Miguel del Campo","article_published_time":"2021-12-07T21:48:15+00:00","article_modified_time":"2021-12-08T08:07:50+00:00","og_image":[{"url":"https:\/\/www.fotografo-profesional.net\/diario\/wp-content\/uploads\/2021\/12\/Fotografo-profesional-en-madrid-LMC-0246.jpg"}],"author":"Luis Miguel del Campo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Miguel del Campo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/","url":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/","name":"Breve historia del viaducto de Madrid - Luis Miguel del Campo","isPartOf":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website"},"datePublished":"2021-12-07T21:48:15+00:00","dateModified":"2021-12-08T08:07:50+00:00","author":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533"},"description":"El viaducto de Madrid no fue siempre como le conocemos hoy en d\u00eda. Desde su primera versi\u00f3n, de 1740, ha sufrido varias transformaciones.","breadcrumb":{"@id":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fotografo-profesional.net\/diario\/2021\/12\/07\/breve-historia-del-viaducto-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.fotografo-profesional.net\/diario\/"},{"@type":"ListItem","position":2,"name":"Breve historia del viaducto de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#website","url":"https:\/\/www.fotografo-profesional.net\/diario\/","name":"Luis Miguel del Campo","description":"Blog de un fot\u00f3grafo profesional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fotografo-profesional.net\/diario\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/220504871d765b4c30a0af1d2fe93533","name":"Luis Miguel del Campo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fotografo-profesional.net\/diario\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84bb1120095136de86f122a882a42d61?s=96&d=mm&r=g","caption":"Luis Miguel del Campo"},"url":"https:\/\/www.fotografo-profesional.net\/diario\/author\/admin_lmdc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/3088"}],"collection":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/comments?post=3088"}],"version-history":[{"count":6,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/3088\/revisions"}],"predecessor-version":[{"id":3097,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/posts\/3088\/revisions\/3097"}],"wp:attachment":[{"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/media?parent=3088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/categories?post=3088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fotografo-profesional.net\/diario\/wp-json\/wp\/v2\/tags?post=3088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}